{"id":383,"date":"2011-10-21T06:24:00","date_gmt":"2011-10-21T06:24:00","guid":{"rendered":"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/"},"modified":"2011-10-21T06:24:00","modified_gmt":"2011-10-21T06:24:00","slug":"microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino","status":"publish","type":"post","link":"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/","title":{"rendered":"Microrrelatos en Servilletas de Papel y El Otro Mundo del Vino"},"content":{"rendered":"<p>Hemos programado una semana muy muy completa: escribir un relato, viajar al otro mundo del vino de la mano de Gonzalo Gonzalo o descubrir los cuentos tradicionales de \u00c1frica&#8230; \u00a1Os esperamos en el Espacio!<\/p>\n<div style=\"clear: both;text-align: center\"><a href=\"http:\/\/3.bp.blogspot.com\/-NVvQJY3lzLA\/TqAeucZ8BbI\/AAAAAAAAADE\/Dth1vnlJ4E0\/s1600\/escribir.jpg\" style=\"clear: left;float: left;margin-bottom: 1em;margin-right: 1em\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"200\" src=\"http:\/\/3.bp.blogspot.com\/-NVvQJY3lzLA\/TqAeucZ8BbI\/AAAAAAAAADE\/Dth1vnlJ4E0\/s200\/escribir.jpg\" width=\"143\" \/><\/a><\/div>\n<p><span style=\"font-size: large\">III Concurso de Microrrelatos en Servilletas de Papel.&nbsp;<\/span><span style=\"color: #990000;font-size: large\">Martes, 25 a las 19:30 h<\/span><br \/><i>Organizado por la Asociaci\u00f3n de Vecinos Los Lirios del Iregua.<\/i><br \/>\u00bfQui\u00e9n no ha garabateado alguna vez un pensamiento o unos versos en una servilleta de papel?<br \/>Ven a escribir tu mini-cuento a la Cafeter\u00eda de Santos Ochoa Castroviejo.&nbsp;<b>La \u00fanica condici\u00f3n es que los escritos quepan en una servilleta de bar por una cara y sobre el tema \u00abBares, qu\u00e9 lugares\u00bb.<\/b><br \/><b><br \/><\/b>Si no puedes venir, los relatos pueden enviarse hasta 30 de octubre, a C\/ L\u00e9rida, 10, 2B, 26006 Logro\u00f1o, poniendo en el sobre \u00abConcurso Literario\u00bb. Consulta las bases en el blog de la Asociaci\u00f3n: <a href=\"http:\/\/www.relatosloslirios.blogspot.com\/\">www.relatosloslirios.blogspot.com<\/a>. <\/p>\n<p><\/p>\n<div style=\"clear: both;text-align: center\"><a href=\"http:\/\/1.bp.blogspot.com\/-o3GM-slBzWI\/TqAfQ5oNm2I\/AAAAAAAAADM\/zSr3mP_bOw8\/s1600\/el-otro-mundo-del-vino.jpg\" style=\"clear: right;float: right;margin-bottom: 1em;margin-left: 1em\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"200\" src=\"http:\/\/1.bp.blogspot.com\/-o3GM-slBzWI\/TqAfQ5oNm2I\/AAAAAAAAADM\/zSr3mP_bOw8\/s200\/el-otro-mundo-del-vino.jpg\" width=\"132\" \/><\/a><\/div>\n<p><span style=\"font-size: large\"><i>El otro mundo del vino<\/i>, Gonzalo Gonzalo<\/span><br \/><span style=\"color: #990000;font-size: large\">Jueves, 27 a las 19:30 h<\/span><br \/><i>PRESENTACI\u00d3N Y CATA<\/i><br \/><b>El otro mundo del vino es un divertido ensayo sobre la cara oculta de la industria vit\u00edcola.<\/b><br \/>Licenciado en Biolog\u00eda y en Enolog\u00eda, Gonzalo Gonzalo Grijalba (Fuenmayor, 1977) ha creado vinos tan singulares como Orgullo, No Phone, Gran Cerdo, Nunca Jam\u00e1s ExNeverland&#8230; e ideado la fiesta enotur\u00edstica Mariquitina&#8217;s Day.<br \/><i>Era necesario reflexionar, observar el oc\u00e9ano del vino, plagado de barcos desorientados y naufragios. Tambi\u00e9n es una forma de hacer justicia. <\/i>Gonzalo Gonzalo.<\/p>\n<p><\/p>\n<div style=\"clear: both;text-align: center\"><a href=\"http:\/\/4.bp.blogspot.com\/-re-DR1UtCi0\/TqAgJRjbQPI\/AAAAAAAAADU\/zq_dgplKq0s\/s1600\/africa.jpg\" style=\"clear: left;float: left;margin-bottom: 1em;margin-right: 1em\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"200\" src=\"http:\/\/4.bp.blogspot.com\/-re-DR1UtCi0\/TqAgJRjbQPI\/AAAAAAAAADU\/zq_dgplKq0s\/s200\/africa.jpg\" width=\"183\" \/><\/a><\/div>\n<p><span style=\"font-size: large\">Cuentacuentos: \u00c1frica<\/span><br \/><span style=\"color: #990000;font-size: large\">S\u00e1bado, 29 de 12 a 13 h<\/span><br \/>Los cuentos son una fuente maravillosa de cultura y tradici\u00f3n popular. Los ni\u00f1os disfrutamos con ellos porque <b>nos ense\u00f1an a entender el mundo en un lenguaje comprensible y simb\u00f3lico<\/b>. Tambi\u00e9n estimulan la imaginaci\u00f3n y transmiten valores humanos. En este cuentacuentos, escucharemos historias tradicionales de \u00c1frica y hablaremos de su sentido y la lecci\u00f3n aprendida.<\/p>\n<p><b>Edad recomendada: <\/b>a partir de 4 a\u00f1os.<br \/><b>Inscripci\u00f3n: <\/b>en la Cafeter\u00eda de Santos Ochoa Castroviejo, en el tel\u00e9fono 941 252 955 o enviando un email a comunicacion@santosochoa.es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hemos programado una semana muy muy completa: escribir un relato, viajar al otro mundo del vino de la mano de Gonzalo Gonzalo o descubrir los cuentos tradicionales de \u00c1frica&#8230; \u00a1Os esperamos en el Espacio! III Concurso de Microrrelatos en Servilletas de Papel.&nbsp;Martes, 25 a las 19:30 hOrganizado por la Asociaci\u00f3n de Vecinos Los Lirios del [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,12,13],"tags":[],"class_list":["post-383","post","type-post","status-publish","format-standard","hentry","category-cuentacuentos","category-libros","category-libros-do-rioja"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Microrrelatos en Servilletas de Papel y El Otro Mundo del Vino - Santos Ochoa Logro\u00f1o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Microrrelatos en Servilletas de Papel y El Otro Mundo del Vino - Santos Ochoa Logro\u00f1o\" \/>\n<meta property=\"og:description\" content=\"Hemos programado una semana muy muy completa: escribir un relato, viajar al otro mundo del vino de la mano de Gonzalo Gonzalo o descubrir los cuentos tradicionales de \u00c1frica&#8230; \u00a1Os esperamos en el Espacio! III Concurso de Microrrelatos en Servilletas de Papel.&nbsp;Martes, 25 a las 19:30 hOrganizado por la Asociaci\u00f3n de Vecinos Los Lirios del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/\" \/>\n<meta property=\"og:site_name\" content=\"Santos Ochoa Logro\u00f1o\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/santosochoalog\" \/>\n<meta property=\"article:published_time\" content=\"2011-10-21T06:24:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.bp.blogspot.com\/-NVvQJY3lzLA\/TqAeucZ8BbI\/AAAAAAAAADE\/Dth1vnlJ4E0\/s200\/escribir.jpg\" \/>\n<meta name=\"author\" content=\"Santos Ochoa Logro\u00f1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@santosochoalog\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Santos Ochoa Logro\u00f1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/\"},\"author\":{\"name\":\"Santos Ochoa Logro\u00f1o\",\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/#\/schema\/person\/103664eb8c60fbeea1880c704687c2e3\"},\"headline\":\"Microrrelatos en Servilletas de Papel y El Otro Mundo del Vino\",\"datePublished\":\"2011-10-21T06:24:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/\"},\"wordCount\":352,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/3.bp.blogspot.com\/-NVvQJY3lzLA\/TqAeucZ8BbI\/AAAAAAAAADE\/Dth1vnlJ4E0\/s200\/escribir.jpg\",\"articleSection\":[\"cuentacuentos\",\"libros\",\"libros do rioja\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/\",\"url\":\"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/\",\"name\":\"Microrrelatos en Servilletas de Papel y El Otro Mundo del Vino - Santos Ochoa Logro\u00f1o\",\"isPartOf\":{\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/3.bp.blogspot.com\/-NVvQJY3lzLA\/TqAeucZ8BbI\/AAAAAAAAADE\/Dth1vnlJ4E0\/s200\/escribir.jpg\",\"datePublished\":\"2011-10-21T06:24:00+00:00\",\"author\":{\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/#\/schema\/person\/103664eb8c60fbeea1880c704687c2e3\"},\"breadcrumb\":{\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/#primaryimage\",\"url\":\"http:\/\/3.bp.blogspot.com\/-NVvQJY3lzLA\/TqAeucZ8BbI\/AAAAAAAAADE\/Dth1vnlJ4E0\/s200\/escribir.jpg\",\"contentUrl\":\"http:\/\/3.bp.blogspot.com\/-NVvQJY3lzLA\/TqAeucZ8BbI\/AAAAAAAAADE\/Dth1vnlJ4E0\/s200\/escribir.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blogs.santosochoa.es\/logrono\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Microrrelatos en Servilletas de Papel y El Otro Mundo del Vino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/#website\",\"url\":\"https:\/\/blogs.santosochoa.es\/logrono\/\",\"name\":\"Santos Ochoa Logro\u00f1o\",\"description\":\"Tu Librer\u00eda Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogs.santosochoa.es\/logrono\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/#\/schema\/person\/103664eb8c60fbeea1880c704687c2e3\",\"name\":\"Santos Ochoa Logro\u00f1o\",\"sameAs\":[\"http:\/\/santosochoa.es\",\"https:\/\/www.facebook.com\/santosochoalog\",\"https:\/\/www.instagram.com\/santosochoalog\/\",\"https:\/\/x.com\/santosochoalog\",\"https:\/\/www.youtube.com\/c\/SantosOchoaLibros\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Microrrelatos en Servilletas de Papel y El Otro Mundo del Vino - Santos Ochoa Logro\u00f1o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/","og_locale":"es_ES","og_type":"article","og_title":"Microrrelatos en Servilletas de Papel y El Otro Mundo del Vino - Santos Ochoa Logro\u00f1o","og_description":"Hemos programado una semana muy muy completa: escribir un relato, viajar al otro mundo del vino de la mano de Gonzalo Gonzalo o descubrir los cuentos tradicionales de \u00c1frica&#8230; \u00a1Os esperamos en el Espacio! III Concurso de Microrrelatos en Servilletas de Papel.&nbsp;Martes, 25 a las 19:30 hOrganizado por la Asociaci\u00f3n de Vecinos Los Lirios del [&hellip;]","og_url":"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/","og_site_name":"Santos Ochoa Logro\u00f1o","article_author":"https:\/\/www.facebook.com\/santosochoalog","article_published_time":"2011-10-21T06:24:00+00:00","og_image":[{"url":"http:\/\/3.bp.blogspot.com\/-NVvQJY3lzLA\/TqAeucZ8BbI\/AAAAAAAAADE\/Dth1vnlJ4E0\/s200\/escribir.jpg","type":"","width":"","height":""}],"author":"Santos Ochoa Logro\u00f1o","twitter_card":"summary_large_image","twitter_creator":"@santosochoalog","twitter_misc":{"Written by":"Santos Ochoa Logro\u00f1o","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/#article","isPartOf":{"@id":"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/"},"author":{"name":"Santos Ochoa Logro\u00f1o","@id":"https:\/\/blogs.santosochoa.es\/logrono\/#\/schema\/person\/103664eb8c60fbeea1880c704687c2e3"},"headline":"Microrrelatos en Servilletas de Papel y El Otro Mundo del Vino","datePublished":"2011-10-21T06:24:00+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/"},"wordCount":352,"commentCount":0,"image":{"@id":"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/#primaryimage"},"thumbnailUrl":"http:\/\/3.bp.blogspot.com\/-NVvQJY3lzLA\/TqAeucZ8BbI\/AAAAAAAAADE\/Dth1vnlJ4E0\/s200\/escribir.jpg","articleSection":["cuentacuentos","libros","libros do rioja"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/","url":"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/","name":"Microrrelatos en Servilletas de Papel y El Otro Mundo del Vino - Santos Ochoa Logro\u00f1o","isPartOf":{"@id":"https:\/\/blogs.santosochoa.es\/logrono\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/#primaryimage"},"image":{"@id":"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/#primaryimage"},"thumbnailUrl":"http:\/\/3.bp.blogspot.com\/-NVvQJY3lzLA\/TqAeucZ8BbI\/AAAAAAAAADE\/Dth1vnlJ4E0\/s200\/escribir.jpg","datePublished":"2011-10-21T06:24:00+00:00","author":{"@id":"https:\/\/blogs.santosochoa.es\/logrono\/#\/schema\/person\/103664eb8c60fbeea1880c704687c2e3"},"breadcrumb":{"@id":"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/#primaryimage","url":"http:\/\/3.bp.blogspot.com\/-NVvQJY3lzLA\/TqAeucZ8BbI\/AAAAAAAAADE\/Dth1vnlJ4E0\/s200\/escribir.jpg","contentUrl":"http:\/\/3.bp.blogspot.com\/-NVvQJY3lzLA\/TqAeucZ8BbI\/AAAAAAAAADE\/Dth1vnlJ4E0\/s200\/escribir.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.santosochoa.es\/logrono\/microrrelatos-en-servilletas-de-papel-y-el-otro-mundo-del-vino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.santosochoa.es\/logrono\/"},{"@type":"ListItem","position":2,"name":"Microrrelatos en Servilletas de Papel y El Otro Mundo del Vino"}]},{"@type":"WebSite","@id":"https:\/\/blogs.santosochoa.es\/logrono\/#website","url":"https:\/\/blogs.santosochoa.es\/logrono\/","name":"Santos Ochoa Logro\u00f1o","description":"Tu Librer\u00eda Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.santosochoa.es\/logrono\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/blogs.santosochoa.es\/logrono\/#\/schema\/person\/103664eb8c60fbeea1880c704687c2e3","name":"Santos Ochoa Logro\u00f1o","sameAs":["http:\/\/santosochoa.es","https:\/\/www.facebook.com\/santosochoalog","https:\/\/www.instagram.com\/santosochoalog\/","https:\/\/x.com\/santosochoalog","https:\/\/www.youtube.com\/c\/SantosOchoaLibros"]}]}},"_links":{"self":[{"href":"https:\/\/blogs.santosochoa.es\/logrono\/wp-json\/wp\/v2\/posts\/383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.santosochoa.es\/logrono\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.santosochoa.es\/logrono\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.santosochoa.es\/logrono\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.santosochoa.es\/logrono\/wp-json\/wp\/v2\/comments?post=383"}],"version-history":[{"count":0,"href":"https:\/\/blogs.santosochoa.es\/logrono\/wp-json\/wp\/v2\/posts\/383\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.santosochoa.es\/logrono\/wp-json\/wp\/v2\/media?parent=383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.santosochoa.es\/logrono\/wp-json\/wp\/v2\/categories?post=383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.santosochoa.es\/logrono\/wp-json\/wp\/v2\/tags?post=383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}