{"id":331,"date":"2012-11-23T11:34:00","date_gmt":"2012-11-23T11:34:00","guid":{"rendered":"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/"},"modified":"2012-11-23T11:34:00","modified_gmt":"2012-11-23T11:34:00","slug":"la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo","status":"publish","type":"post","link":"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/","title":{"rendered":"La cocina de Arzak, la magia de Iurgi y el cuento de Pardo"},"content":{"rendered":"<p><span style=\"font-size: large\"><span style=\"color: #990000\">Xabier Guti\u00e9rrez, director del laboratorio de Arzak, presenta \u201cRecetas sencillas para novatos y cocinillas\u201d<\/span><br \/>Martes 27 de noviembre, a las 19:30 h.<\/span><b><span style=\"color: #0b5394\">&nbsp;<\/span><\/b><\/p>\n<div style=\"clear: both;text-align: center\"><a href=\"http:\/\/1.bp.blogspot.com\/-ZfZVKtbT8ZA\/UK9c7gEME1I\/AAAAAAAAAV0\/u8fnVN0hcTU\/s1600\/recetas-sencillas-xabier-gutierrez.jpg\" style=\"clear: left;float: left;margin-bottom: 1em;margin-right: 1em\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"200\" src=\"http:\/\/1.bp.blogspot.com\/-ZfZVKtbT8ZA\/UK9c7gEME1I\/AAAAAAAAAV0\/u8fnVN0hcTU\/s200\/recetas-sencillas-xabier-gutierrez.jpg\" width=\"155\" \/><\/a><\/div>\n<p><b><span style=\"color: #0b5394\">Soy un libro chiquit\u00edn y de esa manera me puedo colar en tu bolsillo para llevarme por ah\u00ed. Me puedes poner en la encimera de casa mientras cocinas. Y lo m\u00e1s importante, dentro de m\u00ed, encontrar\u00e1s todos los pinchos, tapas, tostas, tartaletas, pulgas, brochetas&#8230; que te puedas imaginar.<\/span><\/b><br \/>Este libro re\u00fane m\u00e1s de 800 recetas divididas en los siguientes apartados: con los dedos, palillo, pan-palillo, pan, pulgas, tostas, tartaletas, platito, brocheta, bol, vasitos, secci\u00f3n ricachones y pintxos en peligro de extinci\u00f3n. Junto a cada receta se indica el grado de dificultad, desde las m\u00e1s simples para novatos en la materia, a las m\u00e1s complicadas para cocinillas, y algunas de grado intermedio para pinches. <\/p>\n<p><b>Xabier Gutierrez<\/b> se define como cocinero, escritor y pensador. Desde hace 20 a\u00f1os est\u00e1 al frente del laboratorio de ideas del Restaurante Arzak, de San Sebasti\u00e1n (Tres Estrellas Michel\u00edn y considerado como uno de los diez mejores del mundo).&nbsp; <br \/>De su paso por la Facultad de Psicolog\u00eda se llev\u00f3 conocimiento. De su paso por la cocina sigue llev\u00e1ndose mucho de su verdadera pasi\u00f3n. De su paso por el mundo culinario-literario, 12 obras en solitario y 7 m\u00e1s en compa\u00f1\u00eda. Tambi\u00e9n se dedica a su blog <a href=\"http:\/\/www.xabiergutierrezcocinero.com\/\" target=\"_blank\">www.xabiergutierrezcocinero.com<\/a>, con el que por ahora se divierte un mont\u00f3n y el d\u00eda que deje de hacerlo, lo dejar\u00e1, as\u00ed de simple.<\/p>\n<p><span style=\"font-size: large\"><span style=\"color: #990000\">El mago Iurgi Sarasa presenta sus mejores trucos <span style=\"font-size: large\">y<\/span> el libro \u201cMagia y magos\u201d<\/span><br \/>Jueves 29 de noviembre, a las 19:30 h.<\/span><b><span style=\"color: #0b5394\">&nbsp;<\/span><\/b><\/p>\n<div style=\"clear: both;text-align: center\"><a href=\"http:\/\/4.bp.blogspot.com\/-BH0LDY73ZtM\/UK9dyCK5E9I\/AAAAAAAAAV8\/hHG6oHApAws\/s1600\/magia-y-magos-iurgi-sarasa.jpg\" style=\"clear: right;float: right;margin-bottom: 1em;margin-left: 1em\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"200\" src=\"http:\/\/4.bp.blogspot.com\/-BH0LDY73ZtM\/UK9dyCK5E9I\/AAAAAAAAAV8\/hHG6oHApAws\/s200\/magia-y-magos-iurgi-sarasa.jpg\" width=\"147\" \/><\/a><\/div>\n<p><b><span style=\"color: #0b5394\">Este manual de iniciaci\u00f3n al ilusionismo tiene tres hilos conductores: relatos, juegos de magia y libros recomendados.<\/span><\/b><br \/>Relatos para iniciarse en la tradici\u00f3n m\u00e1gica, que usted podr\u00e1 utilizar para ambientar sus sesiones de ilusionismo. Aquellos que parecen m\u00e1s fantasiosos sin duda son las historias m\u00e1s reales. Inspirados por cada relato vienen los juegos de magia. Obviando toda t\u00e9cnica manipulativa, tampoco hay nada con trucajes complicados. Prestando especial atenci\u00f3n a las sutilezas psicol\u00f3gicas, que realmente crean la magia en la mente del espectador.<\/p>\n<p><b>Iurgi Sarasa Rosales<\/b> naci\u00f3 en Pamplona en 1962. Es soci\u00f3logo e ilusionista profesional. Recibi\u00f3 formaci\u00f3n teatral en diversas compa\u00f1\u00edas, como \u201cEl lebrel blanco\u201d de Pamplona, dise\u00f1\u00f3 escenograf\u00edas y dirigi\u00f3 montajes esc\u00e9nicos.<br \/>El teatro le llev\u00f3 a interesarse por la magia y se form\u00f3 como ilusionista en Arte-magic, en Vitoria. Presenta espect\u00e1culos de magia, imparte conferencias y tiene una exposici\u00f3n itinerante sobre la magia que ha recorrido importantes festivales. En 1999 public\u00f3 el libro \u201cLa magia: comunicaci\u00f3n social\u201d y en 2009 fue reeditado con el t\u00edtulo \u201cLa magia como t\u00e9cnica de comunicaci\u00f3n\u201d, con pr\u00f3logo de Magic Andreu.<\/p>\n<div style=\"clear: both;text-align: center\"><\/div>\n<p><span style=\"font-size: large\"><span style=\"color: #990000\">Cuentacuentos: Jos\u00e9 Ram\u00f3n Inch\u00e1usti presenta&nbsp; \u201cEl viaje de Pardo\u201d<\/span><br \/>S\u00e1bado 1 de diciembre, de 12 a 13 h.<\/span><br \/><b><span style=\"color: #990000\">Leo y Juego &#8211; Santos Ochoa. Gran V\u00eda, 55, Logro\u00f1o<\/span><\/b><span style=\"color: #0b5394\"><b>&nbsp;<\/b><\/span><\/p>\n<div style=\"clear: both;text-align: center\"><a href=\"http:\/\/3.bp.blogspot.com\/-ONrL6EgXwNo\/UK9e3wGKAUI\/AAAAAAAAAWE\/UXOC5WLVJr0\/s1600\/el-viaje-de-pardo.jpg\" style=\"clear: left;float: left;margin-bottom: 1em;margin-right: 1em\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"150\" src=\"http:\/\/3.bp.blogspot.com\/-ONrL6EgXwNo\/UK9e3wGKAUI\/AAAAAAAAAWE\/UXOC5WLVJr0\/s200\/el-viaje-de-pardo.jpg\" width=\"200\" \/><\/a><\/div>\n<p><span style=\"color: #0b5394\"><b>Pardo es un oso curioso: no le gusta el fr\u00edo, ni la nieve, ni la Navidad&#8230; nunca le han gustado. Un pariente le invita a pasar las pr\u00f3ximas navidades en un lugar donde hace calorcito y sale de viaje sin dudar ni un instante. En vez de llegar a su destino, aparece en un lugar remoto del norte. All\u00ed encuentra una familia de renos que le ayudar\u00e1, pero tendr\u00e1 que disfrazarse de reno y tirar del trineo de Santa Claus y repartir regalos por todo el mundo antes de regresar a su casa.<\/b><\/span><\/p>\n<p><b>Jos\u00e9 Ram\u00f3n Inch\u00e1usti<\/b> naci\u00f3 en Logro\u00f1o en 1973. Es un dibujante y creativo inquieto que ha trabajado como ilustrador de c\u00f3mics, fot\u00f3grafo o monitor de tiempo libre, entre otras cosas. \u201cEl viaje de Pardo\u201d es su primer cuento ilustrado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Xabier Guti\u00e9rrez, director del laboratorio de Arzak, presenta \u201cRecetas sencillas para novatos y cocinillas\u201dMartes 27 de noviembre, a las 19:30 h.&nbsp; Soy un libro chiquit\u00edn y de esa manera me puedo colar en tu bolsillo para llevarme por ah\u00ed. Me puedes poner en la encimera de casa mientras cocinas. Y lo m\u00e1s importante, dentro de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,12],"tags":[],"class_list":["post-331","post","type-post","status-publish","format-standard","hentry","category-cuentacuentos","category-libros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La cocina de Arzak, la magia de Iurgi y el cuento de Pardo - Santos Ochoa Logro\u00f1o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La cocina de Arzak, la magia de Iurgi y el cuento de Pardo - Santos Ochoa Logro\u00f1o\" \/>\n<meta property=\"og:description\" content=\"Xabier Guti\u00e9rrez, director del laboratorio de Arzak, presenta \u201cRecetas sencillas para novatos y cocinillas\u201dMartes 27 de noviembre, a las 19:30 h.&nbsp; Soy un libro chiquit\u00edn y de esa manera me puedo colar en tu bolsillo para llevarme por ah\u00ed. Me puedes poner en la encimera de casa mientras cocinas. Y lo m\u00e1s importante, dentro de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/\" \/>\n<meta property=\"og:site_name\" content=\"Santos Ochoa Logro\u00f1o\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/santosochoalog\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-23T11:34:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/1.bp.blogspot.com\/-ZfZVKtbT8ZA\/UK9c7gEME1I\/AAAAAAAAAV0\/u8fnVN0hcTU\/s200\/recetas-sencillas-xabier-gutierrez.jpg\" \/>\n<meta name=\"author\" content=\"Santos Ochoa Logro\u00f1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@santosochoalog\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Santos Ochoa Logro\u00f1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/\"},\"author\":{\"name\":\"Santos Ochoa Logro\u00f1o\",\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/#\/schema\/person\/103664eb8c60fbeea1880c704687c2e3\"},\"headline\":\"La cocina de Arzak, la magia de Iurgi y el cuento de Pardo\",\"datePublished\":\"2012-11-23T11:34:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/\"},\"wordCount\":659,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/1.bp.blogspot.com\/-ZfZVKtbT8ZA\/UK9c7gEME1I\/AAAAAAAAAV0\/u8fnVN0hcTU\/s200\/recetas-sencillas-xabier-gutierrez.jpg\",\"articleSection\":[\"cuentacuentos\",\"libros\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/\",\"url\":\"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/\",\"name\":\"La cocina de Arzak, la magia de Iurgi y el cuento de Pardo - Santos Ochoa Logro\u00f1o\",\"isPartOf\":{\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/1.bp.blogspot.com\/-ZfZVKtbT8ZA\/UK9c7gEME1I\/AAAAAAAAAV0\/u8fnVN0hcTU\/s200\/recetas-sencillas-xabier-gutierrez.jpg\",\"datePublished\":\"2012-11-23T11:34:00+00:00\",\"author\":{\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/#\/schema\/person\/103664eb8c60fbeea1880c704687c2e3\"},\"breadcrumb\":{\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/#primaryimage\",\"url\":\"http:\/\/1.bp.blogspot.com\/-ZfZVKtbT8ZA\/UK9c7gEME1I\/AAAAAAAAAV0\/u8fnVN0hcTU\/s200\/recetas-sencillas-xabier-gutierrez.jpg\",\"contentUrl\":\"http:\/\/1.bp.blogspot.com\/-ZfZVKtbT8ZA\/UK9c7gEME1I\/AAAAAAAAAV0\/u8fnVN0hcTU\/s200\/recetas-sencillas-xabier-gutierrez.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blogs.santosochoa.es\/logrono\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La cocina de Arzak, la magia de Iurgi y el cuento de Pardo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/#website\",\"url\":\"https:\/\/blogs.santosochoa.es\/logrono\/\",\"name\":\"Santos Ochoa Logro\u00f1o\",\"description\":\"Tu Librer\u00eda Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogs.santosochoa.es\/logrono\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogs.santosochoa.es\/logrono\/#\/schema\/person\/103664eb8c60fbeea1880c704687c2e3\",\"name\":\"Santos Ochoa Logro\u00f1o\",\"sameAs\":[\"http:\/\/santosochoa.es\",\"https:\/\/www.facebook.com\/santosochoalog\",\"https:\/\/www.instagram.com\/santosochoalog\/\",\"https:\/\/x.com\/santosochoalog\",\"https:\/\/www.youtube.com\/c\/SantosOchoaLibros\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La cocina de Arzak, la magia de Iurgi y el cuento de Pardo - Santos Ochoa Logro\u00f1o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/","og_locale":"es_ES","og_type":"article","og_title":"La cocina de Arzak, la magia de Iurgi y el cuento de Pardo - Santos Ochoa Logro\u00f1o","og_description":"Xabier Guti\u00e9rrez, director del laboratorio de Arzak, presenta \u201cRecetas sencillas para novatos y cocinillas\u201dMartes 27 de noviembre, a las 19:30 h.&nbsp; Soy un libro chiquit\u00edn y de esa manera me puedo colar en tu bolsillo para llevarme por ah\u00ed. Me puedes poner en la encimera de casa mientras cocinas. Y lo m\u00e1s importante, dentro de [&hellip;]","og_url":"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/","og_site_name":"Santos Ochoa Logro\u00f1o","article_author":"https:\/\/www.facebook.com\/santosochoalog","article_published_time":"2012-11-23T11:34:00+00:00","og_image":[{"url":"http:\/\/1.bp.blogspot.com\/-ZfZVKtbT8ZA\/UK9c7gEME1I\/AAAAAAAAAV0\/u8fnVN0hcTU\/s200\/recetas-sencillas-xabier-gutierrez.jpg","type":"","width":"","height":""}],"author":"Santos Ochoa Logro\u00f1o","twitter_card":"summary_large_image","twitter_creator":"@santosochoalog","twitter_misc":{"Written by":"Santos Ochoa Logro\u00f1o","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/#article","isPartOf":{"@id":"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/"},"author":{"name":"Santos Ochoa Logro\u00f1o","@id":"https:\/\/blogs.santosochoa.es\/logrono\/#\/schema\/person\/103664eb8c60fbeea1880c704687c2e3"},"headline":"La cocina de Arzak, la magia de Iurgi y el cuento de Pardo","datePublished":"2012-11-23T11:34:00+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/"},"wordCount":659,"commentCount":0,"image":{"@id":"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/#primaryimage"},"thumbnailUrl":"http:\/\/1.bp.blogspot.com\/-ZfZVKtbT8ZA\/UK9c7gEME1I\/AAAAAAAAAV0\/u8fnVN0hcTU\/s200\/recetas-sencillas-xabier-gutierrez.jpg","articleSection":["cuentacuentos","libros"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/","url":"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/","name":"La cocina de Arzak, la magia de Iurgi y el cuento de Pardo - Santos Ochoa Logro\u00f1o","isPartOf":{"@id":"https:\/\/blogs.santosochoa.es\/logrono\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/#primaryimage"},"image":{"@id":"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/#primaryimage"},"thumbnailUrl":"http:\/\/1.bp.blogspot.com\/-ZfZVKtbT8ZA\/UK9c7gEME1I\/AAAAAAAAAV0\/u8fnVN0hcTU\/s200\/recetas-sencillas-xabier-gutierrez.jpg","datePublished":"2012-11-23T11:34:00+00:00","author":{"@id":"https:\/\/blogs.santosochoa.es\/logrono\/#\/schema\/person\/103664eb8c60fbeea1880c704687c2e3"},"breadcrumb":{"@id":"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/#primaryimage","url":"http:\/\/1.bp.blogspot.com\/-ZfZVKtbT8ZA\/UK9c7gEME1I\/AAAAAAAAAV0\/u8fnVN0hcTU\/s200\/recetas-sencillas-xabier-gutierrez.jpg","contentUrl":"http:\/\/1.bp.blogspot.com\/-ZfZVKtbT8ZA\/UK9c7gEME1I\/AAAAAAAAAV0\/u8fnVN0hcTU\/s200\/recetas-sencillas-xabier-gutierrez.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.santosochoa.es\/logrono\/la-cocina-de-arzak-la-magia-de-iurgi-y-el-cuento-de-pardo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.santosochoa.es\/logrono\/"},{"@type":"ListItem","position":2,"name":"La cocina de Arzak, la magia de Iurgi y el cuento de Pardo"}]},{"@type":"WebSite","@id":"https:\/\/blogs.santosochoa.es\/logrono\/#website","url":"https:\/\/blogs.santosochoa.es\/logrono\/","name":"Santos Ochoa Logro\u00f1o","description":"Tu Librer\u00eda Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.santosochoa.es\/logrono\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/blogs.santosochoa.es\/logrono\/#\/schema\/person\/103664eb8c60fbeea1880c704687c2e3","name":"Santos Ochoa Logro\u00f1o","sameAs":["http:\/\/santosochoa.es","https:\/\/www.facebook.com\/santosochoalog","https:\/\/www.instagram.com\/santosochoalog\/","https:\/\/x.com\/santosochoalog","https:\/\/www.youtube.com\/c\/SantosOchoaLibros"]}]}},"_links":{"self":[{"href":"https:\/\/blogs.santosochoa.es\/logrono\/wp-json\/wp\/v2\/posts\/331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.santosochoa.es\/logrono\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.santosochoa.es\/logrono\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.santosochoa.es\/logrono\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.santosochoa.es\/logrono\/wp-json\/wp\/v2\/comments?post=331"}],"version-history":[{"count":0,"href":"https:\/\/blogs.santosochoa.es\/logrono\/wp-json\/wp\/v2\/posts\/331\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.santosochoa.es\/logrono\/wp-json\/wp\/v2\/media?parent=331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.santosochoa.es\/logrono\/wp-json\/wp\/v2\/categories?post=331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.santosochoa.es\/logrono\/wp-json\/wp\/v2\/tags?post=331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}